{"id":4228,"date":"2026-01-31T13:51:37","date_gmt":"2026-01-31T13:51:37","guid":{"rendered":"https:\/\/amniosarchitettura.it\/portfolio\/stringhe-sistemi-di-arredo-continui\/"},"modified":"2026-02-26T07:33:15","modified_gmt":"2026-02-26T07:33:15","slug":"stringhe-sistemi-di-arredo-continui","status":"publish","type":"portfolio","link":"https:\/\/amniosarchitettura.it\/en\/portfolio\/stringhe-sistemi-di-arredo-continui\/","title":{"rendered":"Stringhe Collection: Continuous Designer Furniture"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"4228\" class=\"elementor elementor-4228\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c46893 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3c46893\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3624fe\" data-id=\"c3624fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0bb316 elementor-widget elementor-widget-image\" data-id=\"c0bb316\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_A.webp\" class=\"attachment-full size-full wp-image-4229\" alt=\"Arredo su misura in legno, vetro e acciaio in un salone storico con affreschi e pavimento in legno intarsiato.\" srcset=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_A.webp 2000w, https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_A-300x200.webp 300w, https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_A-1024x682.webp 1024w, https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_A-768x512.webp 768w, https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_A-1536x1024.webp 1536w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad1975d animated-fast elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ad1975d\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;h-neuron-animation--fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6b91d53\" data-id=\"6b91d53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00cf782 elementor-widget elementor-widget-text-editor\" data-id=\"00cf782\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Stringhe is a collection of continuous designer furniture by Amnios Architettura, developed during the renovation of Villino Ferrero and now registered at European level. It includes a sofa, two storage sideboards, a display cabinet and a bed headboard, all united by a single design vision: linear, essential solutions tailored to integrate seamlessly into the space from wall to wall.<\/p><p>The result is a continuous and compact system that merges with the architecture, avoiding unnecessary bulk. Each element develops around wooden planes that, depending on their function, unfold into enclosed volumes, sliding panels or supporting surfaces, often supported by brushed stainless-steel structures that preserve the visual continuity of the floor and visually lighten the furniture.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df646ec\" data-id=\"df646ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9610297 elementor-widget elementor-widget-text-editor\" data-id=\"9610297\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Materiality is another defining feature: stainless steel and oak (or lacquered wood) characterise each component, built from serially repeated sub-modules. This makes every piece modular and easily reproducible, while remaining site-specific \u2014 precisely adaptable to the dimensions and requirements of the space in which it is installed.<\/p><p class=\"translation-block\">Stringhe proposes an architectural, linear and flexible solution that respects the space and enhances the void, making it more open and liveable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf86dcd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"bf86dcd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af49abe\" data-id=\"af49abe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-205a526 animated-fast m-neuron-gallery--layout-masonry l-neuron-grid-wrapper--columns__2 l-neuron-grid-wrapper-tablet--columns__2 l-neuron-grid-wrapper-mobile--columns__2 m-neuron-gallery--overlay-none l-neuron-grid-wrapper--offset-no elementor-invisible elementor-widget elementor-widget-neuron-gallery\" data-id=\"205a526\" data-element_type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;rem&quot;,&quot;size&quot;:3.5,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;rem&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;neuron_animations&quot;:&quot;h-neuron-animation--fadeIn&quot;,&quot;neuron_animations_duration&quot;:&quot;animated-fast&quot;,&quot;_animation&quot;:&quot;h-neuron-animation--fadeIn&quot;,&quot;layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;2&quot;,&quot;carousel&quot;:&quot;no&quot;,&quot;animation_delay&quot;:0,&quot;image_animation_hover&quot;:&quot;none&quot;}\" data-widget_type=\"neuron-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n\t\t\n\t\t\t\t<div class=\"l-neuron-grid\" data-masonry-id=\"25c793091eae299d81af02d8d4a76994\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4244\" data-elementor-lightbox-title=\"Design e funzionalit\u00e0: i vani sagomati accolgono le bottiglie integrandosi nel volume della madia.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_Z.webp\" alt=\"Primo piano di una madia moderna grigia con vani porta bottiglie in lamiera di acciaio e pavimento in legno a spina di pesce.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4243\" data-elementor-lightbox-title=\"Equilibrio cromatico e funzionale: la madia attrezzata diventa protagonista dello spazio living.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_Y.webp\" alt=\"Madia moderna grigio antracite con vani porta bottiglie integrati, piano in rovere e pianta decorativa in un interno di design.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4242\" data-elementor-lightbox-title=\"Ottimizzazione degli spazi: la testiera diventa libreria e contenitore grazie a moduli geometrici personalizzati.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_R.webp\" alt=\"Testiera del letto moderna integrata in una scaffalatura in legno con moduli bianchi a obl\u00f2 e lampade a sospensione minimali.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4241\" data-elementor-lightbox-title=\"Ottimizzazione degli spazi: la testiera diventa libreria e contenitore grazie a moduli geometrici personalizzati.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_Q.webp\" alt=\"Testiera del letto moderna integrata in una scaffalatura in legno con moduli bianchi a obl\u00f2 e lampade a sospensione minimali.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4240\" data-elementor-lightbox-title=\"Ottimizzazione degli spazi: la testiera diventa libreria e contenitore grazie a moduli geometrici personalizzati.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_P.webp\" alt=\"Testiera del letto moderna integrata in una scaffalatura in legno con moduli bianchi a obl\u00f2 e lampade a sospensione minimali.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4239\" data-elementor-lightbox-title=\"Vista superiore di una madia contenitiva con piano in rovere massello sagomato per ospitare vino\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_O.webp\" alt=\"dettaglio scasso nel legno massello per sede bottiglie di vino\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4238\" data-elementor-lightbox-title=\"Un mobile in rovere e profilati di acciaio inox, con ante a battente e a ribalta. Il piano \u00e8 sagomato per poter alloggiare bottiglie di vino\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_N.webp\" alt=\"Mobile per sala da pranzo con scassi nel legno massello per ospitare bottiglie di vino\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4237\" data-elementor-lightbox-title=\"L&#039;ordine come elemento d&#039;arredo: mensole in rovere e barattoli trasparenti ritmano la parete della sala da pranzo in comunicazione con la cucina. \">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_M.webp\" alt=\"Sala da pranzo con lunghe mensole in legno, e madia integrata su misura con ante a ribalta per contenere delle bottiglie di vino.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4236\" data-elementor-lightbox-title=\"L&#039;ordine come elemento d&#039;arredo: mensole in rovere e barattoli trasparenti ritmano la parete della sala da pranzo in comunicazione con la cucina. \">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_L.webp\" alt=\"Sala da pranzo con lunghe mensole in legno, e madia integrata su misura con ante a ribalta per contenere delle bottiglie di vino.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4235\" data-elementor-lightbox-title=\"L&#039;ordine come elemento d&#039;arredo: mensole in rovere e barattoli trasparenti ritmano la parete della sala da pranzo in comunicazione con la cucina.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_I.webp\" alt=\"Sala da pranzo con lunghe mensole in legno, barattoli in vetro ordinati e pavimento in graniglie a scacchi bianco e nero.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4234\" data-elementor-lightbox-title=\"Luce e storia: la modularit\u00e0 del divano asseconda la geometria delle aperture originali del salone.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_F.webp\" alt=\"Salone moderno in palazzo storico con quattro finestre a obl\u00f2 decorate di epoca liberty , fregio affrescato e divani minimalisti su misura su pedana in legno.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4233\" data-elementor-lightbox-title=\"Luce e storia: la modularit\u00e0 del divano asseconda la geometria delle aperture originali del salone.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_E.webp\" alt=\"Salone moderno in palazzo storico con quattro finestre a obl\u00f2 decorate di epoca liberty , fregio affrescato e divani minimalisti su misura su pedana in legno.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4232\" data-elementor-lightbox-title=\"L&#039;essenza del progetto: matericit\u00e0 naturale e rigore metallico in perfetta armonia.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_D.webp\" alt=\"Primo piano del piano in rovere massello e montante in acciaio inox satinato con viti a vista.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4231\" data-elementor-lightbox-title=\"La cura del dettaglio: piedini in acciaio inox satinato progettati per garantire stabilit\u00e0 millimetrica su superfici storiche.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_C.webp\" alt=\"Dettaglio tecnico del piedino livellatore regolabile in acciaio inox per scaffalatura su misura e pavimento in legno antico.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"l-neuron-grid__item m-neuron-gallery__item\" data-elementor-open-lightbox=\"no\" data-elementor-lightbox-slideshow=\"all-205a526\" data-id=\"4230\" data-elementor-lightbox-title=\"Trasparenze e solidit\u00e0: l&#039;anta in vetro protegge senza nascondere la bellezza del rovere massello.\">\n\n\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__inner\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail--link\">\n\t\t\t\t\t\t\t\t\t<div class=\"m-neuron-gallery__thumbnail\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/amniosarchitettura.it\/wp-content\/uploads\/2026\/01\/STRINGHE-_-SISTEMI-DI-ARREDO-CONTINUI_B.webp\" alt=\"Dettaglio di una credenza moderna su misura con anta in vetro temperato, ripiani in rovere e struttura in acciaio inox satinato.\" \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Stringhe \u00e8 una linea di arredi su misura progettata da Amnios Architettura, nata durante la ristrutturazione di Villino Ferrero e oggi brevettata a livello europeo. Si compone di un divano, due madie contenitive, una vetrinetta e una spalliera da letto, tutti uniti da un\u2019unica visione progettuale: soluzioni lineari, essenziali, capaci di integrarsi sartorialmente nello spazio&#8230;<\/p>","protected":false},"author":1,"featured_media":4229,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"portfolio_category":[33],"portfolio_tag":[],"class_list":["post-4228","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-design"],"_links":{"self":[{"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/portfolio\/4228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/comments?post=4228"}],"version-history":[{"count":14,"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/portfolio\/4228\/revisions"}],"predecessor-version":[{"id":5213,"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/portfolio\/4228\/revisions\/5213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/media\/4229"}],"wp:attachment":[{"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/media?parent=4228"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/portfolio_category?post=4228"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/amniosarchitettura.it\/en\/wp-json\/wp\/v2\/portfolio_tag?post=4228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}